{"id":703,"date":"2026-04-24T17:11:39","date_gmt":"2026-04-24T15:11:39","guid":{"rendered":"https:\/\/topnews24.ma\/factoryacademy\/?p=703"},"modified":"2026-04-24T17:11:46","modified_gmt":"2026-04-24T15:11:46","slug":"introduction-au-financement-et-coproduction","status":"publish","type":"post","link":"https:\/\/topnews24.ma\/factoryacademy\/2026\/04\/24\/introduction-au-financement-et-coproduction\/","title":{"rendered":"Introduction au financement et coproduction"},"content":{"rendered":"\n<p>Bienvenue dans le cours \u00ab&nbsp;Jouer pour la t\u00e9l\u00e9vision&nbsp;\u00bb, con\u00e7u pour vous aider \u00e0 ma\u00eetriser les techniques et les nuances n\u00e9cessaires \u00e0 des performances convaincantes \u00e0 l&rsquo;\u00e9cran.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<h3 class=\"wp-block-heading\"><strong>Aper\u00e7u du cours<\/strong><\/h3>\n\n\n\n<p>Ce cours se concentre sur les comp\u00e9tences sp\u00e9cifiques n\u00e9cessaires aux acteurs pour jouer efficacement devant la cam\u00e9ra. Vous apprendrez \u00e0 adapter votre jeu aux gros plans, \u00e0 comprendre la dynamique de la cam\u00e9ra et \u00e0 livrer des performances naturelles et subtiles, id\u00e9ales pour la t\u00e9l\u00e9vision. Gr\u00e2ce \u00e0 des exercices pratiques et \u00e0 des mises en situation, vous d\u00e9velopperez votre capacit\u00e9 \u00e0 cr\u00e9er un lien avec le public tout en maintenant une pr\u00e9cision technique irr\u00e9prochable sur le plateau.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Principaux r\u00e9sultats d&rsquo;apprentissage<\/strong><\/h3>\n\n\n\n<ol class=\"wp-block-list\">\n<li>Comprendre les diff\u00e9rences entre le jeu d&rsquo;acteur au th\u00e9\u00e2tre et le jeu d&rsquo;acteur \u00e0 l&rsquo;\u00e9cran.<\/li>\n\n\n\n<li>Apprenez \u00e0 jouer de mani\u00e8re naturelle et authentique devant la cam\u00e9ra.<\/li>\n\n\n\n<li>Adaptez vos expressions et vos mouvements aux gros plans et aux diff\u00e9rents types de plans.<\/li>\n\n\n\n<li>D\u00e9velopper une conscience des angles de cam\u00e9ra, du cadrage et de la continuit\u00e9.<\/li>\n\n\n\n<li>D\u00e9velopper la confiance en soi pour offrir des prestations t\u00e9l\u00e9vis\u00e9es coh\u00e9rentes et captivantes.<\/li>\n<\/ol>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/topnews24.ma\/factoryacademy\/wp-content\/uploads\/2026\/04\/viviane.png\" alt=\"\" class=\"wp-image-495\" srcset=\"https:\/\/topnews24.ma\/factoryacademy\/wp-content\/uploads\/2026\/04\/viviane.png 500w, https:\/\/topnews24.ma\/factoryacademy\/wp-content\/uploads\/2026\/04\/viviane-300x300.png 300w, https:\/\/topnews24.ma\/factoryacademy\/wp-content\/uploads\/2026\/04\/viviane-150x150.png 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<p><strong>Dur\u00e9e :<\/strong>&nbsp;4 heures<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bienvenue dans le cours \u00ab&nbsp;Jouer pour la t\u00e9l\u00e9vision&nbsp;\u00bb, con\u00e7u pour vous aider \u00e0 ma\u00eetriser les techniques et les nuances n\u00e9cessaires \u00e0 des performances convaincantes \u00e0 l&rsquo;\u00e9cran. Aper\u00e7u du cours Ce cours se concentre sur les comp\u00e9tences sp\u00e9cifiques n\u00e9cessaires aux acteurs pour jouer efficacement devant la cam\u00e9ra. Vous apprendrez \u00e0 adapter votre jeu aux gros plans, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":447,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[],"class_list":["post-703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-production-gestion-de-projets"],"_links":{"self":[{"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/posts\/703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/comments?post=703"}],"version-history":[{"count":1,"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/posts\/703\/revisions"}],"predecessor-version":[{"id":707,"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/posts\/703\/revisions\/707"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/media\/447"}],"wp:attachment":[{"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/media?parent=703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/categories?post=703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/topnews24.ma\/factoryacademy\/wp-json\/wp\/v2\/tags?post=703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}